{"id":3085,"date":"2023-05-07T17:15:16","date_gmt":"2023-05-07T15:15:16","guid":{"rendered":"https:\/\/rencartaumelies.com\/?p=3085"},"modified":"2026-08-04T18:03:39","modified_gmt":"2026-08-04T16:03:39","slug":"mon-crime-de-francois-ozon","status":"publish","type":"post","link":"https:\/\/rencartaumelies.org\/index.php\/2023\/05\/07\/mon-crime-de-francois-ozon\/","title":{"rendered":"MON CRIME de Fran\u00e7ois OZON"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"420\" src=\"https:\/\/rencartaumelies.org\/wp-content\/uploads\/2023\/05\/Mon-crime-2.jpg\" alt=\"\" class=\"wp-image-8888\" srcset=\"https:\/\/rencartaumelies.org\/wp-content\/uploads\/2023\/05\/Mon-crime-2.jpg 310w, https:\/\/rencartaumelies.org\/wp-content\/uploads\/2023\/05\/Mon-crime-2-221x300.jpg 221w\" sizes=\"auto, (max-width: 310px) 100vw, 310px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Et puis il y a les films-pains au chocolat ! Les films qui ne pr\u00e9tendent pas vous apprendre quelque chose, qui ne pr\u00e9tendent pas vous faire r\u00e9fl\u00e9chir\u2026 quoique, tout peut inspirer de la r\u00e9flexion, m\u00eame une com\u00e9die p\u00e9tillante comme des bulles de campagne. M\u00eame que pendant le g\u00e9n\u00e9rique de fin vous vous levez, vous vous retournez pour prendre votre manteau pos\u00e9 sur le dossier de votre fauteuil et l\u00e0, devant le sourire de ravi de la cr\u00e8che de votre voisin de derri\u00e8re, vous lui dites : \u00ab On s\u2019est bien amus\u00e9, n\u2019est-ce pas ? \u00bb Et lui : \u00ab Oh oui\u2026 et puis elles sont CHARMANTES ! \u00bb et vous le sentez tomb\u00e9 amoureux des deux !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9j\u00e0, elles m\u2019avaient fait de l\u2019\u0153il sur l\u2019affiche du film, placard\u00e9e dans les couloirs du m\u00e9tro et sur les colonnes Morris depuis quelques semaines. Nadia la blonde et Rebecca la brune. Rose et jaune d\u2019or, avec un petit parfum ann\u00e9es 1930\u2026 une promesse de sucre, cette affiche !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Promesse tenue : c\u2019est du th\u00e9\u00e2tre de boulevard, ripolin\u00e9 fa\u00e7on Me Too. Donc c\u2019est plein d\u2019anachronismes, on ne parlait pas comme \u00e7a on ne PENSAIT pas comme \u00e7a dans ces ann\u00e9es-l\u00e0, mais on s\u2019en fiche, parce qu\u2019on sent bien que le r\u00e9alisateur n\u2019a pas laiss\u00e9 la vraisemblance pointer le bout de son vilain nez sur son tournage ! Et puis cette histoire de deux jeunes femmes, l\u2019une actrice au ch\u00f4mage, l\u2019autre avocate au ch\u00f4mdu, tirant le diable par la queue dans le petit appartement miteux qu\u2019elles se partagent pour se serrer les coudes, c\u2019est le pr\u00e9texte \u00e0 des dialogues qui fusent, des rebondissements farfelus, des personnages secondaires hauts en couleur. Dont une Isabelle Huppert qui en fait des caisses, elle est absolument incapable de subtilit\u00e9 dans la com\u00e9die mais \u00e7a va bien \u00e0 son personnage de diva sur le retour, d\u00e9termin\u00e9e \u00e0 r\u00e9cup\u00e9rer son crime, qu\u2019on lui a vol\u00e9 !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est amusant, c\u2019est charmant, \u00e7a ne casse pas trois pattes \u00e0 un canard mais pourquoi casser trois pattes \u00e0 un canard ? Trois pattes, c\u2019est m\u00e9chant !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Isabelle DEVAUX<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et puis il y a les films-pains au chocolat ! Les films qui ne pr\u00e9tendent pas vous apprendre quelque chose, qui ne pr\u00e9tendent pas vous [&#8230;]<\/p>\n","protected":false},"author":54,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3085","post","type-post","status-publish","format-standard","hentry","category-passion"],"_links":{"self":[{"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/posts\/3085","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/comments?post=3085"}],"version-history":[{"count":3,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/posts\/3085\/revisions"}],"predecessor-version":[{"id":8889,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/posts\/3085\/revisions\/8889"}],"wp:attachment":[{"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/media?parent=3085"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/categories?post=3085"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rencartaumelies.org\/index.php\/wp-json\/wp\/v2\/tags?post=3085"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}